{"id":12472,"date":"2019-10-28T14:40:36","date_gmt":"2019-10-28T17:40:36","guid":{"rendered":"https:\/\/www.kaspersky.com.br\/blog\/?p=12472"},"modified":"2020-05-20T14:05:06","modified_gmt":"2020-05-20T17:05:06","slug":"kaspersky-next-2019","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/kaspersky-next-2019\/12472\/","title":{"rendered":"5 coisas que aprendemos no Kaspersky NEXT"},"content":{"rendered":"<p>O evento Kaspersky NEXT deste ano apresentou pesquisas e discuss\u00f5es de alguns dos especialistas mais proeminentes da Europa na \u00e1rea de ciberseguran\u00e7a e intelig\u00eancia artificial. Desde o aprendizado de m\u00e1quina e IA at\u00e9 a prote\u00e7\u00e3o da IdC, eis aqui cinco coisas que aprendemos no evento deste ano, que aconteceu em 14 de outubro, em Lisboa.<\/p>\n<h3><strong>Usando IA para tornar o mundo mais justo<\/strong><\/h3>\n<p>Voc\u00ea j\u00e1 pensou em quantas decis\u00f5es as m\u00e1quinas tomaram hoje? Ou quantas foram baseadas em g\u00eanero, ra\u00e7a ou origem? Provavelmente, voc\u00ea nem percebe quantas decis\u00f5es s\u00e3o tomadas pela intelig\u00eancia artificial ao inv\u00e9s de um ser humano. Kriti Sharma, fundador da AI for Good, explicou que algoritmos est\u00e3o sendo usados \u200b\u200bo tempo todo para tomar decis\u00f5es sobre quem somos e o que queremos.<\/p>\n<p>Kriti tamb\u00e9m ressaltou que o que realmente precisamos fazer para melhorar a intelig\u00eancia artificial \u00e9 reunir pessoas de todos os tipos de origens, g\u00eaneros e etnias. <a href=\"https:\/\/www.ted.com\/talks\/kriti_sharma_how_to_keep_human_biases_out_of_ai\" target=\"_blank\" rel=\"noopener nofollow\">Aqui voc\u00ea pode assistir ao Ted Talk<\/a> sobre porque o vi\u00e9s humano influencia a tomada de decis\u00e3o da m\u00e1quina <a href=\"https:\/\/www.ted.com\/talks\/kriti_sharma_how_to_keep_human_biases_out_of_ai\" target=\"_blank\" rel=\"noopener nofollow\">aqui.<\/a><\/p>\n<h3><strong>O impacto da atribui\u00e7\u00e3o de g\u00eanero \u00e0 IA<\/strong><\/h3>\n<p>Pense em Alexa, Siri e Cortana. O que todas t\u00eam em comum? Usam vozes femininas e s\u00e3o feitas para serem servas obedientes. Por que \u00e9 assim? A tecnologia est\u00e1 refor\u00e7ando os estere\u00f3tipos? Dois pain\u00e9is de discuss\u00e3o sobre g\u00eanero e IA foram investigados. Assistentes digitais t\u00eam vozes femininas porque, como v\u00e1rios estudos determinaram, as pessoas se sentem mais confort\u00e1veis \u200b\u200bcom as vozes femininas como assistentes digitais. Isso tamb\u00e9m \u00e9 um reflexo da sociedade?<\/p>\n<p>Ent\u00e3o, o que pode ser feito para combater a desigualdade de g\u00eanero na IA? Talvez usar uma voz neutra em termos de g\u00eanero ou talvez criar um g\u00eanero para rob\u00f4s e IA. Al\u00e9m de abordar esse problema (e mencionado acima), tamb\u00e9m \u00e9 importante ter equipes plurais criando IA, refletindo a diversidade dos usu\u00e1rios atendidos.<\/p>\n<p><a href=\"https:\/\/twitter.com\/kaspersky\/status\/1183739717965230087\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/twitter.com\/kaspersky\/status\/1183739717965230087<\/a><\/p>\n<h3><strong>Confiamos mais nos rob\u00f4s do que nas pessoas<\/strong><\/h3>\n<p>Um rob\u00f4 social \u00e9 um sistema de intelig\u00eancia artificial que interage com humanos e outros rob\u00f4s \u2013 e que, ao contr\u00e1rio de Siri ou Cortana, tem uma presen\u00e7a f\u00edsica. Tony Balpaeme, professor de rob\u00f3tica da Universidade de Ghent, explicou como os problemas relacionados \u00e0s intera\u00e7\u00f5es entre rob\u00f4s e humanos aumentar\u00e3o \u00e0 medida que os rob\u00f4s se tornarem mais presentes no nosso cotidiano.<\/p>\n<p>Balpaeme descreveu alguns dos experimentos cient\u00edficos que ele e sua equipe realizaram. Por exemplo, testaram a habilidade de humanos <em>versus<\/em> a de rob\u00f4s em extrair informa\u00e7\u00f5es confidenciais (data de nascimento, endere\u00e7o ou cidade onde morou na inf\u00e2ncia, cor favorita etc.) que poderiam ser usadas para redefinir senhas. O engra\u00e7ado \u00e9 que os rob\u00f4s s\u00e3o mais confi\u00e1veis \u200b\u200bdo que as pessoas, ent\u00e3o \u00e9 mais prov\u00e1vel que as pessoas lhes deem informa\u00e7\u00f5es confidenciais.<\/p>\n<p>Ele tamb\u00e9m apresentou um experimento para invas\u00e3o f\u00edsica. Um grupo de pessoas encarregadas de proteger um edif\u00edcio ou uma \u00e1rea permite facilmente um rob\u00f4 bonitinho entrar na \u00e1rea. N\u00e3o h\u00e1 raz\u00e3o para supor que o rob\u00f4 \u00e9 seguro, mas os humanos assumem que ele \u00e9 inofensivo \u2013 uma tend\u00eancia altamente explor\u00e1vel. Voc\u00ea pode <a href=\"https:\/\/securelist.com\/robots-social-impact\/94431\/\" target=\"_blank\" rel=\"noopener\">ler mais sobre rob\u00f3tica social e experimentos relacionados<\/a> no Securelist.<\/p>\n<p><a href=\"https:\/\/twitter.com\/kaspersky\/status\/1183683889514078209\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/twitter.com\/kaspersky\/status\/1183683889514078209<\/a><\/p>\n<h3><strong>A IA criar\u00e1 <em>deepfakes<\/em> muito convincentes<\/strong><\/h3>\n<p>David Jacoby, membro do Kaspersky GReAT, falou sobre engenharia social: chat bots, IA e amea\u00e7as automatizadas. Com o tempo, os aplicativos de reconhecimento facial e de voz podem ser explorados por meio de engenharia social ou outros m\u00e9todos da velha guarda.<\/p>\n<p>Jacoby tamb\u00e9m falou sobre <em>deepfakes<\/em>, que est\u00e3o se tornando muito mais dif\u00edceis de detectar. Como elas podem afetar futuras elei\u00e7\u00f5es e transmiss\u00f5es de not\u00edcias \u00e9 uma grande preocupa\u00e7\u00e3o.<\/p>\n<p>O principal problema \u00e9 a confian\u00e7a. Depois que a tecnologia for aperfei\u00e7oada, em quem voc\u00ea confiar\u00e1? A solu\u00e7\u00e3o, segundo ele, \u00e9 uma melhor conscientiza\u00e7\u00e3o: educa\u00e7\u00e3o e novas tecnologias para ajudar os usu\u00e1rios a detectar v\u00eddeos falsos.<br>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-12474\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2019\/10\/28143738\/kaspersky-next-2019-photo1.png\" alt=\"\" width=\"885\" height=\"616\"><\/p>\n<h3><strong>O estado de seguran\u00e7a na rob\u00f3tica<\/strong><\/h3>\n<p>Dmitry Galov, outro membro do GReAT da Kaspersky, falou sobre o ROS (Sistema de Opera\u00e7\u00e3o de Rob\u00f4s, na sigla em ingl\u00eas), uma estrutura flex\u00edvel para escrever software de rob\u00f4. Como muitos outros sistemas, o ROS n\u00e3o foi criado com a seguran\u00e7a em mente e, naturalmente, possui importantes problemas de seguran\u00e7a. Ent\u00e3o, antes que produtos baseados em ROS, como rob\u00f4s sociais e carros aut\u00f4nomos, voem das salas de aula das universidades para os bra\u00e7os dos consumidores, os criadores devem resolver esses problemas. De fato, uma nova vers\u00e3o do ROS est\u00e1 em intenso desenvolvimento. Voc\u00ea pode ler mais no <a href=\"https:\/\/securelist.com\/robots-social-impact\/94431\/\" target=\"_blank\" rel=\"noopener\">relat\u00f3rio de Galov<\/a>.<\/p>\n<p><strong>Dica b\u00f4nus: use preservativos USB<\/strong><\/p>\n<p>Marco Preuss e Dan Demeter, membros do GReAT da Kaspersky, falaram sobre como as pessoas se protegem contra hackers enquanto viajam a neg\u00f3cios. Voc\u00ea j\u00e1 pensou que poderia haver c\u00e2meras escondidas, bugs e <a href=\"https:\/\/www.wikihow.com\/Tell-if-a-Mirror-Is-Two-Way-or-Not\" target=\"_blank\" rel=\"noopener nofollow\">espelhos falsos<\/a> no seu quarto do hotel?<br>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-12475\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2019\/10\/28143842\/kaspersky-next-2019-photo2.png\" alt=\"\" width=\"939\" height=\"704\">Para aqueles que s\u00e3o levemente paranoicos, <a href=\"https:\/\/www.kaspersky.com.br\/blog\/travel-security-five-tips\/11849\/\" target=\"_blank\" rel=\"noopener\">este post inclui algumas dicas de seguran\u00e7a de viagem<\/a> de Preuss e Demeter, que tamb\u00e9m falaram sobre a import\u00e2ncia (se voc\u00ea \u00e9 realmente paranoico) de usar um \u201cpreservativo\u201d USB \u2013 sim, eles realmente existem e seu uso \u00e9 an\u00e1logo aos produzidos para humanos: se voc\u00ea estiver prestes a carregar o telefone usando uma porta USB desconhecida, vale a pena proteger seu dispositivo com este min\u00fasculo gadget. A boa not\u00edcia \u00e9 que diferentemente dos preservativos normais, eles s\u00e3o reutiliz\u00e1veis.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"ksc-trial-generic\">\n","protected":false},"excerpt":{"rendered":"<p>Este ano o evento do Kaspersky NEXT girou ao redor de IA, igualdade de g\u00eanero e rob\u00f3tica social<\/p>\n","protected":false},"author":26,"featured_media":12473,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,45],"tags":[1382,1342,1433,2077,200,2011],"class_list":{"0":"post-12472","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"category-special-projects","9":"tag-aprendizado-de-maquina","10":"tag-ia","11":"tag-igualdade-de-genero","12":"tag-kaspersky-next-ia","13":"tag-noticias","14":"tag-projetos-especiais"},"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/kaspersky-next-2019\/12472\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/kaspersky-next-2019\/16787\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/kaspersky-next-2019\/14176\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/kaspersky-next-2019\/18774\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/kaspersky-next-2019\/16821\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/kaspersky-next-2019\/15566\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/kaspersky-next-2019\/19476\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/kaspersky-next-2019\/18134\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/kaspersky-next-2019\/23789\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/kaspersky-next-2019\/6558\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/kaspersky-next-2019\/28979\/"},{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/kaspersky-next-2019\/12427\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/kaspersky-next-2019\/11345\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/kaspersky-next-2019\/20379\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/kaspersky-next-2019\/24366\/"},{"hreflang":"nl","url":"https:\/\/www.kaspersky.nl\/blog\/kaspersky-next-2019\/24325\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/kaspersky-next-2019\/19244\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/kaspersky-next-2019\/23556\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/kaspersky-next-2019\/23406\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/projetos-especiais\/","name":"projetos especiais"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/12472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12472"}],"version-history":[{"count":3,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/12472\/revisions"}],"predecessor-version":[{"id":15265,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/12472\/revisions\/15265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/12473"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=12472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=12472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}