{"id":14811,"date":"2020-04-14T19:05:15","date_gmt":"2020-04-14T22:05:15","guid":{"rendered":"https:\/\/www.kaspersky.com.br\/blog\/?p=14811"},"modified":"2020-04-14T19:25:19","modified_gmt":"2020-04-14T22:25:19","slug":"what-is-bec-attack","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/what-is-bec-attack\/14811\/","title":{"rendered":"Como lidar com ataques BEC"},"content":{"rendered":"<p>Os cibercriminosos est\u00e3o constantemente \u00e0 procura de novas maneiras de atacar as empresas. Nos \u00faltimos anos, t\u00eam recorrido cada vez mais a ataques de <a href=\"https:\/\/www.kaspersky.com.br\/blog\/bec-toyota\/12427\/\" target=\"_blank\" rel=\"noopener\">comprometimento de e-mail corporativo<\/a> (BEC, na sigla em ingl\u00eas), direcionados \u00e0s mensagens empresariais.<\/p>\n<p>Somente o Centro de Den\u00fancias de Crimes na Internet (IC3) dos EUA <a href=\"https:\/\/pdf.ic3.gov\/2019_IC3Report.pdf\" target=\"_blank\" rel=\"noopener nofollow\">notificou 23.775 desses incidentes ao FBI em 2019<\/a> \u2013 aumento de 3.500 em rela\u00e7\u00e3o <a href=\"https:\/\/pdf.ic3.gov\/2018_IC3Report.pdf\" target=\"_blank\" rel=\"noopener nofollow\">a 2018<\/a>, com danos pulando de US $ 1,2 bilh\u00e3o para US $ 1,7 bilh\u00e3o.<\/p>\n<h2>O que \u00e9 um ataque BEC?<\/h2>\n<p>Um ataque BEC \u00e9 definido como uma campanha cibercriminosa direcionada, que funciona do seguinte modo:<\/p>\n<ol>\n<li>In\u00edcio de uma troca de e-mail com um funcion\u00e1rio da empresa ou assumindo o controle de uma conta existente;<\/li>\n<li>Conquistar a confian\u00e7a do funcion\u00e1rios;<\/li>\n<li>Incentivar a\u00e7\u00f5es que sejam prejudiciais aos interesses da empresa ou de seus clientes.<\/li>\n<\/ol>\n<p>Geralmente, essas a\u00e7\u00f5es est\u00e3o relacionadas \u00e0 transfer\u00eancia de fundos para as contas dos criminosos ou ao envio de arquivos confidenciais, mas n\u00e3o se restringem a isso. Por exemplo, nossos especialistas encontraram recentemente uma solicita\u00e7\u00e3o que parecia vir do CEO de uma empresa, com instru\u00e7\u00f5es para enviar c\u00f3digos de cart\u00f5es-presente em mensagens de texto para algum n\u00famero de telefone.<\/p>\n<p>Embora as tentativas de ataques BEC geralmente usem truques no estilo de <a href=\"https:\/\/www.kaspersky.com.br\/blog\/phishing-prevalence-effect\/13773\/\" target=\"_blank\" rel=\"noopener\">phishing<\/a>, o ataque \u00e9 um pouco mais sofisticado, com um p\u00e9 em conhecimento tecnol\u00f3gico e outro em engenharia social. Al\u00e9m disso, as t\u00e9cnicas usadas s\u00e3o \u00fanicas: as mensagens n\u00e3o cont\u00eam links ou anexos maliciosos, mas os golpistas tentam enganar o dono do e-mail e, portanto, o destinat\u00e1rio, a considerar a mensagem leg\u00edtima. \u00c9 a engenharia social que tem o papel principal.<\/p>\n<p>Uma coleta cuidadosa de dados sobre a v\u00edtima geralmente precede um ataque; o cibercriminoso usa essas informa\u00e7\u00f5es depois para ganhar a confian\u00e7a do alvo. A correspond\u00eancia pode consistir em apenas duas ou tr\u00eas mensagens ou pode durar v\u00e1rios meses.<\/p>\n<p>Como informa\u00e7\u00e3o importante, vale a pena destacar que os ataques BEC de combinam v\u00e1rios cen\u00e1rios e tecnologias. Por exemplo, os cibercriminosos podem primeiro roubar as credenciais de um trabalhador comum usando spear phishing e, em seguida, lan\u00e7ar um ataque contra um funcion\u00e1rio de alto escal\u00e3o da empresa.<\/p>\n<h2>Cen\u00e1rios mais comuns de ataques BEC<\/h2>\n<p>J\u00e1 existem alguns cen\u00e1rios comuns de ataque BEC, mas os cibercriminosos est\u00e3o sempre inventando novos. De acordo com nossas observa\u00e7\u00f5es, a maioria dos casos \u00e9 redut\u00edvel a uma das quatro seguintes variantes:<\/p>\n<ul>\n<li><strong>Parceiros comerciais fakes<\/strong>. O cibercriminoso se passa por um representante de uma organiza\u00e7\u00e3o com a qual a empresa do destinat\u00e1rio trabalha. \u00c0s vezes, \u00e9 uma empresa real que a v\u00edtima realmente tem contato por motivos corporativos. Em outros casos, os golpistas tentam enganar as v\u00edtimas desatentas fingindo representar uma empresa falsa.<\/li>\n<li><strong>Instru\u00e7\u00f5es do chefe<\/strong>. Aqui, os cibercriminosos criam uma mensagem falsa em nome de um gerente (geralmente de alto escal\u00e3o) usando truques t\u00e9cnicos ou engenharia social.<\/li>\n<li><strong>Mensagem de um advogado<\/strong>. Os golpistas escrevem para um funcion\u00e1rio de alto escal\u00e3o (\u00e0s vezes at\u00e9 para o CEO) com urg\u00eancia e, acima de tudo, exigindo fundos confidenciais ou dados sens\u00edveis. Frequentemente, representam um contratado, como um contador externo, fornecedor ou empresa de log\u00edstica. No entanto, a maioria das situa\u00e7\u00f5es que exigem uma resposta urgente e confidencial \u00e9 de natureza legal, portanto as mensagens geralmente s\u00e3o enviadas em nome de um advogado ou escrit\u00f3rio de advocacia.<\/li>\n<li><strong>Sequestro de e-mail<\/strong>. O invasor obt\u00e9m acesso ao e-mail do funcion\u00e1rio e emite uma instru\u00e7\u00e3o para transferir fundos ou enviar dados, ou ainda inicia uma troca de mensagens com as pessoas autorizadas a fazer tais opera\u00e7\u00f5es. Essa estrat\u00e9gia \u00e9 especialmente perigosa porque o invasor pode visualizar as mensagens na caixa de sa\u00edda, facilitando a imita\u00e7\u00e3o do estilo de comunica\u00e7\u00e3o do funcion\u00e1rio.<\/li>\n<\/ul>\n<h2>T\u00e9cnicas de ataques BEC<\/h2>\n<p>Os ataques do BEC tamb\u00e9m est\u00e3o se desenvolvendo do ponto de vista tecnol\u00f3gico. Se em 2013 costumavam usar as contas de e-mail hackeadas de CEOs ou CFOs, hoje dependem cada vez mais de imitar com sucesso outra pessoa por meio de uma combina\u00e7\u00e3o de subterf\u00fagios t\u00e9cnicos, engenharia social e falta de aten\u00e7\u00e3o por parte da v\u00edtima. Aqui est\u00e3o os truques t\u00e9cnicos b\u00e1sicos utilizados:<\/p>\n<ul>\n<li><strong>Remetente de e-mail falsificado<\/strong>. O golpista falsifica os cabe\u00e7alhos do e-mail. Como resultado, por exemplo, uma mensagem enviada de <em>phisher@email.com<\/em> parece vir de <em>CEO@suacompanhia.com<\/em> na caixa de entrada da v\u00edtima. Este m\u00e9todo tem muitas varia\u00e7\u00f5es e cabe\u00e7alhos diferentes podem ser alterados de v\u00e1rias maneiras. O principal perigo desse m\u00e9todo de ataque \u00e9 que n\u00e3o apenas os invasores podem manipular os cabe\u00e7alhos das mensagens \u2013 por v\u00e1rios motivos, os remetentes leg\u00edtimos tamb\u00e9m podem faz\u00ea-lo.<\/li>\n<li><strong>Dom\u00ednios parecidos.<\/strong> O cibercriminoso registra um nome de dom\u00ednio muito semelhante ao da v\u00edtima. Por exemplo, examp1e.com em vez de example.com. Em seguida, as mensagens s\u00e3o enviadas do endere\u00e7o <em>CEO@examp1e.com<\/em> na esperan\u00e7a de que um funcion\u00e1rio descuidado n\u00e3o consiga identificar o dom\u00ednio falso. A dificuldade aqui reside no fato de o invasor ser o propriet\u00e1rio do dom\u00ednio falso, de modo que as informa\u00e7\u00f5es sobre o remetente v\u00e3o passar sem problemas em todas as verifica\u00e7\u00f5es de seguran\u00e7a tradicionais.<\/li>\n<li><strong>Mailsploits<\/strong>. Novas vulnerabilidades sempre s\u00e3o encontradas em clientes de e-mail. \u00c0s vezes, eles podem ser usados \u200b\u200bpara for\u00e7ar o cliente a exibir um nome falso ou endere\u00e7o do remetente. Felizmente, essas vulnerabilidades rapidamente chamam a aten\u00e7\u00e3o das empresas de seguran\u00e7a da informa\u00e7\u00e3o, permitindo que as solu\u00e7\u00f5es de seguran\u00e7a rastreiem seu uso e evitem ataques.<\/li>\n<li><strong>Sequestro de e-mail.<\/strong> Os invasores obt\u00eam acesso total a uma conta de e-mail, e podem enviar mensagens quase indistingu\u00edveis das reais. A \u00fanica maneira de se proteger automaticamente contra esse tipo de ataque \u00e9 usar ferramentas de aprendizado de m\u00e1quina para determinar a autoria dos e-mails.<\/li>\n<\/ul>\n<h2>Casos que encontramos<\/h2>\n<p>Respeitamos a confidencialidade de nossos clientes, portanto, a seguir, n\u00e3o s\u00e3o mensagens reais, mas exemplos que ilustram algumas possibilidades comuns de ataques BEC.<\/p>\n<h3>Nome falso<\/h3>\n<p>O impostor tenta estabelecer contato com uma v\u00edtima em potencial, se passando por seu chefe. Para que o destinat\u00e1rio n\u00e3o tente entrar em contato com o seu superior verdadeiro, o golpista destaca a urg\u00eancia da solicita\u00e7\u00e3o e a atual indisponibilidade por outros canais de comunica\u00e7\u00e3o:<\/p>\n<div id=\"attachment_14813\" style=\"width: 598px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-14813\" class=\"wp-image-14813 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2020\/04\/14185552\/what-is-BEC-attack-Example-1.png\" alt=\"O truque do nome falso\" width=\"588\" height=\"343\"><p id=\"caption-attachment-14813\" class=\"wp-caption-text\">O truque do nome falso<\/p><\/div>\n<h3><\/h3>\n<p>Uma an\u00e1lise mais detalhada revela que o nome do remetente (Bob) n\u00e3o corresponde ao endere\u00e7o de e-mail real (<em>not_bob@gmail.com<\/em>). Nesse caso, o invasor falsificou apenas o nome exibido quando a mensagem \u00e9 aberta. Esse tipo de ataque \u00e9 especialmente eficaz em dispositivos m\u00f3veis, que por padr\u00e3o exibem apenas o nome do remetente, n\u00e3o o endere\u00e7o.<\/p>\n<h3>Endere\u00e7o falso<\/h3>\n<p>O cibercriminoso procura um funcion\u00e1rio da contabilidade que esteja autorizado a alterar dados banc\u00e1rios, escrevendo:<\/p>\n<div id=\"attachment_14814\" style=\"width: 849px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-14814\" class=\"wp-image-14814 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2020\/04\/14185717\/what-is-BEC-attack-Example2.jpg\" alt=\"O truque dos dados falsos\" width=\"839\" height=\"227\"><p id=\"caption-attachment-14814\" class=\"wp-caption-text\">O truque dos dados falsos<\/p><\/div>\n<p>Aqui, o cabe\u00e7alho da mensagem \u00e9 alterado para que o cliente exiba o nome e o endere\u00e7o de e-mail do funcion\u00e1rio leg\u00edtimo, mas o e-mail do invasor \u00e9 fornecido como endere\u00e7o de resposta. Consequentemente, as respostas a esta mensagem s\u00e3o enviadas para <em>not_bob@gmail.com<\/em>. Muitos clientes ocultam o campo de resposta por padr\u00e3o, portanto, essa mensagem parece genu\u00edna mesmo em inspe\u00e7\u00e3o minuciosa. Na teoria, um ataque usando essa mensagem poderia ser interrompido configurando corretamente o SPF, DKIM e DMARC no servidor de e-mail corporativo.<\/p>\n<h3>Falsifica\u00e7\u00e3o fantasma<\/h3>\n<p>O criminoso, fingindo ser gerente, convence o funcion\u00e1rio da necessidade de cooperar com um advogado falso, que supostamente entrar\u00e1 em contato em breve:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-5e70eeba51857832bf015352 size-full\" src=\"https:\/\/s3-eu-west-1.amazonaws.com\/kdaily-prod\/wp-content\/uploads\/sites\/92\/2020\/03\/17113730\/what-is-BEC-attack-Example-3-EN.jpg\" alt=\"The ghost spoofing trick\" width=\"680\" height=\"312\"><\/p>\n<p>Aqui, o campo do remetente cont\u00e9m n\u00e3o apenas o nome, mas tamb\u00e9m o endere\u00e7o de e-mail falso. N\u00e3o \u00e9 a t\u00e9cnica mais avan\u00e7ada, mas ainda assim muitas pessoas caem nela, principalmente se o endere\u00e7o real n\u00e3o for exibido na tela do destinat\u00e1rio (por exemplo, porque \u00e9 muito longo).<\/p>\n<h3>Dom\u00ednio parecido<\/h3>\n<p>Outro cibercriminoso tenta iniciar uma troca de e-mail com um funcion\u00e1rio da empresa:<\/p>\n<div id=\"attachment_14816\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-14816\" class=\"wp-image-14816 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2020\/04\/14185915\/what-is-BEC-attack-Example-4.jpg\" alt=\"O truque do dom\u00ednio parecido\" width=\"722\" height=\"167\"><p id=\"caption-attachment-14816\" class=\"wp-caption-text\">O truque do dom\u00ednio parecido<\/p><\/div>\n<p>Este \u00e9 um exemplo do m\u00e9todo de dom\u00ednio semelhante, que mencionamos acima. O fraudador registra primeiro um nome de dom\u00ednio parecido com o confi\u00e1vel (neste caso, examp1e.com em vez de example.com) e, em seguida, espera que o destinat\u00e1rio n\u00e3o perceba.<\/p>\n<h2>Ataques BEC contra executivos de alto n\u00edvel<\/h2>\n<p>V\u00e1rias not\u00edcias recentes destacaram os ataques BEC que causaram danos significativos a empresas todos os portes e de diversas maneiras. Aqui est\u00e3o alguns dos mais interessantes:<\/p>\n<ul>\n<li>Um cibercriminosos criou um dom\u00ednio imitando o de um fabricante de eletr\u00f4nicos de Taiwan e o usou para enviar faturas para grandes empresas (<a href=\"https:\/\/www.theregister.co.uk\/2019\/03\/21\/facebook_google_scam\/\" target=\"_blank\" rel=\"noopener nofollow\">incluindo Facebook e Google<\/a>) por um per\u00edodo de dois anos, embolsando US$ 120 milh\u00f5es no processo.<\/li>\n<li>Fingindo fazer parte de uma empresa do setor de constru\u00e7\u00e3o, cibercriminosos convenceram a Universidade do Sul do Oregon a <a href=\"https:\/\/www.ibtimes.com\/fradulent-email-business-email-compromise-attack-costs-southern-oregon-university-2m-2551724\" target=\"_blank\" rel=\"noopener nofollow\">transferir quase US$ 2 milh\u00f5es para contas falsas<\/a>.<\/li>\n<li>Alguns fraudadores interferiram na correspond\u00eancia entre dois clubes de futebol, registrando um dom\u00ednio contendo o nome de um deles, mas com uma extens\u00e3o de dom\u00ednio diferente. Os dois clubes, Boca Juniors e Paris Saint-Germain, estavam discutindo a transfer\u00eancia de um jogador e a comiss\u00e3o sobre o acordo. Como resultado, quase <a href=\"https:\/\/www.kaspersky.com.br\/blog\/boca-juniors-case\/11867\/\" target=\"_blank\" rel=\"noopener\">\u20ac 520 mil foram para v\u00e1rias contas de<\/a> cibercriminosos no M\u00e9xico.<\/li>\n<li>O bra\u00e7o europeu da Toyota <a href=\"https:\/\/www.kaspersky.com.br\/blog\/bec-toyota\/12427\/\" target=\"_blank\" rel=\"noopener\">perdeu mais de US$ 37 milh\u00f5es<\/a> para cibercriminosos como consequ\u00eancia de uma orienta\u00e7\u00e3o falsa de transfer\u00eancia banc\u00e1ria que um funcion\u00e1rio considerou leg\u00edtima.<\/li>\n<\/ul>\n<h2>Como lidar com ataques BEC<\/h2>\n<p>Os cibercriminosos usam uma gama bastante ampla de truques t\u00e9cnicos e m\u00e9todos de engenharia social para ganhar confian\u00e7a e realizar fraudes. No entanto, tomar v\u00e1rias medidas eficazes pode minimizar a amea\u00e7a de ataques do BEC:<\/p>\n<ul>\n<li>Configure o SPF, use assinaturas DKIM e implemente uma pol\u00edtica DMARC para se proteger contra correspond\u00eancias internas falsas. Em teoria, essas medidas tamb\u00e9m permitem que outras empresas autentiquem e-mails enviados em nome da sua organiza\u00e7\u00e3o (supondo, \u00e9 claro, que as empresas tenham essas tecnologias configuradas). Este m\u00e9todo <a href=\"https:\/\/www.kaspersky.com.br\/blog\/36c3-fake-emails\/13910\/\" target=\"_blank\" rel=\"noopener\">\u00e9 insuficiente em alguns aspectos<\/a> (como n\u00e3o \u00e9 poss\u00edvel impedir a falsifica\u00e7\u00e3o de fantasmas ou dom\u00ednios semelhantes), mas quanto mais empresas usam SPF, DKIM e DMARC, menor se torna o espa\u00e7o de atua\u00e7\u00e3o dos cibercriminosos. O uso dessas tecnologias contribui para um tipo de imunidade coletiva contra muitos tipos de opera\u00e7\u00f5es maliciosas com cabe\u00e7alhos de e-mail.<\/li>\n<li>Treine funcion\u00e1rios periodicamente para combater engenharia social. Uma <a href=\"https:\/\/k-asap.com\/pt\/?icid=br_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder____kasap___\" target=\"_blank\" rel=\"noopener\">combina\u00e7\u00e3o de oficinas e simula\u00e7\u00f5es<\/a> prepara os funcion\u00e1rios para ficarem atentos e identificarem ataques BEC que eventualmente possam burlar outras camadas de defesa.<\/li>\n<li>Use <a href=\"https:\/\/www.kaspersky.com.br\/small-to-medium-business-security?icid=br_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\">solu\u00e7\u00f5es de seguran\u00e7a<\/a> com <a href=\"https:\/\/www.kaspersky.com.br\/small-to-medium-business-security\/microsoft-office-365-security?icid=br_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder____kso365___\" target=\"_blank\" rel=\"noopener\">tecnologias especializadas contra ataques BEC<\/a> para vencer os v\u00e1rios vetores de ataque descritos neste post.<\/li>\n<\/ul>\n<p>As solu\u00e7\u00f5es Kaspersky com filtragem de conte\u00fado, especialmente criadas em nosso laborat\u00f3rio, j\u00e1 identificam muitos tipos de ataques BEC e nossos especialistas desenvolvem continuamente tecnologias para proteger ainda mais contra os golpes mais avan\u00e7ados e sofisticados.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"kesb-gartner\">\n","protected":false},"excerpt":{"rendered":"<p>Empresas de todo o mundo s\u00e3o regularmente v\u00edtimas de ataques BEC. Explicamos os perigos e como minimiz\u00e1-lo.<\/p>\n","protected":false},"author":2569,"featured_media":14812,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1119,1655],"tags":[2065,1185,1125,2272,221],"class_list":{"0":"post-14811","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business","8":"category-enterprise","9":"tag-bec","10":"tag-business","11":"tag-e-mail","12":"tag-mail","13":"tag-phishing"},"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/what-is-bec-attack\/14811\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/what-is-bec-attack\/19587\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/what-is-bec-attack\/16127\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/what-is-bec-attack\/21158\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/what-is-bec-attack\/19421\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/what-is-bec-attack\/17937\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/what-is-bec-attack\/22178\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/what-is-bec-attack\/20990\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/what-is-bec-attack\/27623\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/what-is-bec-attack\/7936\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/what-is-bec-attack\/34135\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/what-is-bec-attack\/13181\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/what-is-bec-attack\/23416\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/what-is-bec-attack\/27902\/"},{"hreflang":"nl","url":"https:\/\/www.kaspersky.nl\/blog\/what-is-bec-attack\/25144\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/what-is-bec-attack\/21831\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/what-is-bec-attack\/27040\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/what-is-bec-attack\/26879\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/business\/","name":"Business"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/14811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/2569"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=14811"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/14811\/revisions"}],"predecessor-version":[{"id":14818,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/14811\/revisions\/14818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/14812"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=14811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=14811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=14811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}