{"id":17331,"date":"2021-04-20T17:28:54","date_gmt":"2021-04-20T20:28:54","guid":{"rendered":"https:\/\/www.kaspersky.com.br\/blog\/?p=17331"},"modified":"2022-05-05T09:01:12","modified_gmt":"2022-05-05T12:01:12","slug":"apps-falsos-auxilio-emergencial-google-play","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/apps-falsos-auxilio-emergencial-google-play\/17331\/","title":{"rendered":"Apps falsos sobre aux\u00edlio emergencial inundam Google Play"},"content":{"rendered":"<p>Com a recente libera\u00e7\u00e3o das primeiras parcelas para o novo aux\u00edlio emergencial 2021, \u00e9 importante ficar atenta para n\u00e3o cair em poss\u00edveis golpes digitais nos pr\u00f3ximos dias. Nossos pesquisadores localizaram uma s\u00e9rie de aplicativos falsos na <a href=\"https:\/\/www.kaspersky.com.br\/blog\/dresscode-android-trojan\/6643\/\" target=\"_blank\" rel=\"noopener\">Play Store<\/a> que prometem consultas ao valor do aux\u00edlio emergencial, calend\u00e1rios de pagamentos e outros detalhes.<\/p>\n<p>Apesar de os apps n\u00e3o pedirem nenhum dado pessoal, alguns chegam a solicitar o n\u00famero do PIS (identifica\u00e7\u00e3o social que pode ser consultada nos extratos do FGTS, no Cart\u00e3o Cidad\u00e3o ou na Carteira de Trabalho). Al\u00e9m disso, os aplicativos falsos exibem muita propaganda ao longo do uso \u2013 e de forma bastante invasiva -, garantindo pageviews ao criador. Para incentivar o uso, enviam uma grande quantidade de notifica\u00e7\u00f5es, que s\u00e3o exibidas pelo menos a cada 10 minutos, pedindo para o usu\u00e1rio abrir o app. Desta forma, garantem mais visualiza\u00e7\u00f5es nas propagandas, muitas n\u00e3o s\u00e3o relacionadas ao aux\u00edlio emergencial.<\/p>\n<p>\u201cExiste uma grande possibilidade desses aplicativos se tornarem, eventualmente, maliciosos. Basta apenas uma atualiza\u00e7\u00e3o do desenvolvedor para que comecem a pedir dados pessoais dos usu\u00e1rios. Dessa forma, os cibercriminosos ter\u00e3o informa\u00e7\u00f5es pessoais e financeiras \u2013 inclusive, os mesmos que desviaram milh\u00f5es nos pagamentos do aux\u00edlio no ano passado\u201d, explica Fabio Assolini, analista s\u00eanior de seguran\u00e7a da Kaspersky.<\/p>\n<div id=\"attachment_17332\" style=\"width: 790px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-17332\" class=\"wp-image-17332 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2021\/04\/20161719\/1776006162low.jpeg\" alt=\"Exemplos de apps falsos relacionados ao Aux\u00edlio Emergencial dispon\u00edveis na Google Play\" width=\"780\" height=\"289\"><p id=\"caption-attachment-17332\" class=\"wp-caption-text\">Exemplos de apps falsos relacionados ao Aux\u00edlio Emergencial dispon\u00edveis na Google Play<\/p><\/div>\n<p>\u00a0<\/p>\n<p>Fabio ainda ressalta que quando algu\u00e9m instala o app falso, muitas vezes o usu\u00e1rio ser\u00e1 direcionado \u2013 ap\u00f3s a exibi\u00e7\u00e3o de muita propaganda \u2013 para o site da Caixa Econ\u00f4mica Federal. Apesar de n\u00e3o serem maliciosos no momento, comprometem a privacidade dos usu\u00e1rios e colocam informa\u00e7\u00f5es pessoais em risco.<\/p>\n<div id=\"attachment_17333\" style=\"width: 194px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-17333\" class=\"wp-image-17333 size-medium\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2021\/04\/20171953\/982875808low-184x300.jpeg\" alt=\"Imagem de um dos apps falsos com diversas notifica\u00e7\u00f5es ao usu\u00e1rio\" width=\"184\" height=\"300\"><p id=\"caption-attachment-17333\" class=\"wp-caption-text\">Imagem de um dos apps falsos com diversas notifica\u00e7\u00f5es ao usu\u00e1rio<\/p><\/div>\n<p>\u00a0<\/p>\n<p>Essa n\u00e3o \u00e9 a primeira vez que o aux\u00edlio emergencial \u00e9 usado como mote por cibercriminosos. Em dezembro de 2020, uma not\u00edcia falsa circulou nas redes sociais sobre um \u201c<a href=\"https:\/\/www.kaspersky.com.br\/blog\/abono-emergencial-natal-golpe\/16288\/\" target=\"_blank\" rel=\"noopener\">Abono Emergencial de Natal<\/a>\u201c, que direcionava os internautas a clicar em links maliciosos.<\/p>\n<h2>N\u00e3o seja v\u00edtima<\/h2>\n<ul>\n<li>Suspeite sempre de links recebidos por e-mails, SMSs ou <a href=\"https:\/\/www.kaspersky.com.br\/blog\/privacidade-dados-golpes-dicas\/16880\/\" target=\"_blank\" rel=\"noopener\">mensagens de WhatsApp<\/a>, principalmente quando o endere\u00e7o parece suspeito ou estranho.<\/li>\n<li>Sempre verifique o endere\u00e7o do site para onde foi redirecionado, endere\u00e7o do link e o e-mail do remetente para garantir que s\u00e3o genu\u00ednos antes de clicar, al\u00e9m de verificar se o nome do link na mensagem n\u00e3o aponta para outro hyperlink.<\/li>\n<li>Verifique se a not\u00edcia \u00e9 verdadeira acessando o site oficial da empresa ou organiza\u00e7\u00e3o \u2013 ou os perfis nas redes sociais.<\/li>\n<li>Se n\u00e3o tiver certeza de que o app \u00e9 real e seguro, n\u00e3o insira informa\u00e7\u00f5es pessoais.<\/li>\n<li>Use <a href=\"https:\/\/www.kaspersky.com.br\/premium?icid=br_bb2022-kdplacehd_acq_ona_smm__onl_b2c_kdaily_lnk_sm-team___kprem___\" target=\"_blank\" rel=\"noopener\">solu\u00e7\u00f5es de seguran\u00e7a confi\u00e1veis<\/a> para ter uma prote\u00e7\u00e3o em tempo real para quaisquer tipos de amea\u00e7as.<\/li>\n<\/ul>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"b2cpromo\">\n","protected":false},"excerpt":{"rendered":"<p>Apesar de n\u00e3o maliciosos, aplicativos exibem propaganda n\u00e3o relacionada ao aux\u00edlio e podem se tornar perigosos no futuro.<\/p>\n","protected":false},"author":2706,"featured_media":16291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12,14],"tags":[830,313,1025,134],"class_list":{"0":"post-17331","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tips","8":"category-news","9":"tag-tips","10":"tag-golpes","11":"tag-google-play","12":"tag-whatsapp"},"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/apps-falsos-auxilio-emergencial-google-play\/17331\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/golpes\/","name":"Golpes"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/17331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/2706"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=17331"}],"version-history":[{"count":1,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/17331\/revisions"}],"predecessor-version":[{"id":17334,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/17331\/revisions\/17334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/16291"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=17331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=17331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=17331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}