{"id":17496,"date":"2021-05-17T10:10:18","date_gmt":"2021-05-17T13:10:18","guid":{"rendered":"https:\/\/www.kaspersky.com.br\/blog\/?p=17496"},"modified":"2022-05-05T09:01:10","modified_gmt":"2022-05-05T12:01:10","slug":"5-things-that-you-must-update-asap","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/5-things-that-you-must-update-asap\/17496\/","title":{"rendered":"Cinco coisas para atualizar o mais r\u00e1pido poss\u00edvel"},"content":{"rendered":"<p>Fique tranquilo, n\u00e3o h\u00e1 uma conspira\u00e7\u00e3o global para incomod\u00e1-lo com notifica\u00e7\u00f5es de atualiza\u00e7\u00e3o. Um software sem os patches de atualiza\u00e7\u00e3o permite muitos ciberataques \u2013 por isso os desenvolvedores est\u00e3o constantemente corrigindo vulnerabilidades em seus programas e voc\u00ea recebendo alertas sobre updates. Atualize o software, corrija as vulnerabilidades e frustre os bandidos.<\/p>\n<p>Pesquisamos as <a href=\"https:\/\/www.kaspersky.com\/blog\/device-updates-report\/\" target=\"_blank\" rel=\"noopener nofollow\">atitudes dos usu\u00e1rios<\/a> sobre atualiza\u00e7\u00f5es em duas dezenas de pa\u00edses. Descobrimos que a grande maioria das pessoas que entrevistamos tende a clicar em \u201cLembre-me mais tarde\u201d. J\u00e1 que \u00e9 assim, aqui est\u00e1 uma lista dos cinco tipos de software mais importantes para atualizar \u2013 os que valem a pena parar de trabalhar ou se divertir.<\/p>\n<h2>1. Sistema operacional<\/h2>\n<p>O sistema operacional \u00e9 a engrenagem interna necess\u00e1ria para que todos os programas em seu computador ou dispositivo m\u00f3vel sejam executados. Portanto, problemas de seguran\u00e7a aqui podem ter consequ\u00eancias muito s\u00e9rias. Explorando uma vulnerabilidade no SO, os cibercriminosos podem criptografar seus dados e <a href=\"https:\/\/www.kaspersky.com.br\/blog\/brasileiros-alvo-metade-ransomware\/16562\/\" target=\"_blank\" rel=\"noopener\">exigir um resgate<\/a>, <a href=\"https:\/\/www.kaspersky.com.br\/blog\/miner-in-your-office\/11985\/\" target=\"_blank\" rel=\"noopener\">minerar criptomoedas<\/a> em seu hardware, interceptar seus detalhes de pagamento, descobrir materiais para extors\u00e3o e muito mais.<\/p>\n<p>Os ataques ao sistema operacional s\u00e3o alguns dos ataques mais massivos e destrutivos que existem. Por exemplo, por meio de uma vulnerabilidade no Windows, o ransomware <a href=\"https:\/\/www.kaspersky.com.br\/blog\/wannacry-is-still-alive\/11120\/\" target=\"_blank\" rel=\"noopener\">WannaCry<\/a> e <a href=\"https:\/\/www.kaspersky.com.br\/blog\/expetr-for-b2b\/9223\/\" target=\"_blank\" rel=\"noopener\">NotPetya<\/a> comprometeu centenas de milhares de computadores em todo o mundo, levando a perdas na casa dos bilh\u00f5es de d\u00f3lares (leia mais <a href=\"https:\/\/www.kaspersky.com.br\/blog\/history-of-ransomware\/17280\/\" target=\"_blank\" rel=\"noopener\">aqui<\/a>). As atualiza\u00e7\u00f5es do Windows que teriam impedido os ataques \u2013 h\u00e1 muito estavam dispon\u00edveis para download no momento dos surtos.<\/p>\n<p>Rastrear e corrigir vulnerabilidades em sistemas operacionais \u00e9 um processo cont\u00ednuo, portanto, as atualiza\u00e7\u00f5es devem ser regulares. Isso se aplica a computadores e dispositivos m\u00f3veis.<\/p>\n<h2>2. Navegador<\/h2>\n<p>Os navegadores tamb\u00e9m podem dar aos invasores acesso a um dispositivo. Por exemplo, os cibercriminosos podem injetar um script malicioso no c\u00f3digo do site para ataques <a href=\"https:\/\/encyclopedia.kaspersky.com\/glossary\/drive-by-attack\/\" target=\"_blank\" rel=\"noopener\">drive-by<\/a>\u00a0(as v\u00edtimas precisam apenas abrir uma p\u00e1gina da Web para acionar o malware).<\/p>\n<p>Os criadores de um exploit para o Chrome realizaram tal ataque, usando uma vulnerabilidade do navegador para baixar um Trojan para os computadores das v\u00edtimas. Embora os desenvolvedores do Chrome tenham lan\u00e7ado rapidamente uma atualiza\u00e7\u00e3o que corrigiu a vulnerabilidade, os usu\u00e1rios que adiaram a instala\u00e7\u00e3o permaneceram presas f\u00e1ceis.<\/p>\n<p>N\u00e3o se esque\u00e7a dos navegadores pr\u00e9-instalados, como Safari ou Edge. Mesmo que voc\u00ea o tenha aberto apenas uma vez para baixar o Firefox ou o Chrome, ele ainda est\u00e1 l\u00e1. Alguns ataques controlam programas que est\u00e3o simplesmente no sistema, independentemente de serem usados ou n\u00e3o. Os usu\u00e1rios de vers\u00f5es do iOS e iPadOS anteriores a 14.2 tiveram que lidar com um <a href=\"https:\/\/www.kaspersky.com.br\/blog\/ios-critical-vulnerabilities-124\/12138\/\" target=\"_blank\" rel=\"noopener\">bug no mecanismo do Safari<\/a> que permitia aos invasores executarem outros programas.<\/p>\n<h2>3. Software de produtividade do escrit\u00f3rio<\/h2>\n<p>Estamos sempre visualizando e editando documentos, ent\u00e3o n\u00e3o deve ser surpresa que os cibercriminosos geralmente usam bugs no Microsoft Office e nos pacotes da Adobe para ataques.<\/p>\n<p>Por exemplo, os cibercriminosos usaram uma vulnerabilidade no <a href=\"https:\/\/threatpost.com\/necurs-based-dde-attacks-now-spreading-locky-ransomware\/128554\/\" target=\"_blank\" rel=\"noopener nofollow\">recurso DDE do Microsoft Word<\/a> para baixar o ransomware Locky nos dispositivos das v\u00edtimas. Seguiu-se um pedido de resgate, com a amea\u00e7a de destruir ou publicar dados confidenciais. Pouco depois, a Microsoft <a href=\"https:\/\/www.bleepingcomputer.com\/news\/microsoft\/microsoft-disables-dde-feature-in-word-to-prevent-further-malware-attacks\/\" target=\"_blank\" rel=\"noopener nofollow\">lan\u00e7ou um patch<\/a>. Moral da hist\u00f3ria: para manter seus arquivos, reputa\u00e7\u00e3o e dinheiro protegidos, atualize os softwares usados no dia a dia do escrit\u00f3rio o quanto antes.<\/p>\n<h2>4. Aplicativos de banco<\/h2>\n<p>Os aplicativos financeiros est\u00e3o entre os alvos mais interessantes para os cibercriminosos porque um ataque bem-sucedido os coloca diretamente em contato com o dinheiro da v\u00edtima. Os bancos entendem isso, \u00e9 claro, e atualizam constantemente seus aplicativos para melhorar a prote\u00e7\u00e3o. O principal \u00e9 instalar as atualiza\u00e7\u00f5es assim que estiverem dispon\u00edveis.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"kis-banking\">\n<h2>5. Software antiv\u00edrus<\/h2>\n<p>Nem \u00e9 preciso dizer que voc\u00ea tamb\u00e9m precisa manter seu software de seguran\u00e7a atualizado. Novos Trojans e v\u00edrus aparecem todos os dias; somente no segundo semestre de 2020, nossos produtos de seguran\u00e7a <a href=\"https:\/\/securelist.com\/it-threat-evolution-q2-2020-pc-statistics\/98292\/\" target=\"_blank\" rel=\"noopener\">detectaram ataques<\/a> de 80 milh\u00f5es de objetos maliciosos exclusivos. Para mant\u00ea-lo protegido contra ciberinvas\u00f5es, sua prote\u00e7\u00e3o antiv\u00edrus precisa de atualiza\u00e7\u00f5es regulares e oportunas.<\/p>\n<p>Seu antiv\u00edrus provavelmente j\u00e1 \u00e9 atualizado por padr\u00e3o, o que \u00e9 conveniente e centrado na seguran\u00e7a, mas para ter certeza, verifique as configura\u00e7\u00f5es. Tanto o software antiv\u00edrus quanto os bancos de dados de malware dos quais ele depende precisam de atualiza\u00e7\u00f5es regulares e autom\u00e1ticas.<\/p>\n<h2>Checklist<\/h2>\n<p>Se voc\u00ea deseja que seu computador e smartphone funcionem e protejam seus dados pessoais por um longo tempo, \u00e9 importante considerar a prote\u00e7\u00e3o em todos os n\u00edveis, incluindo atualiza\u00e7\u00f5es oportunas de software, em particular:<\/p>\n<p>\u25cf Sistemas operacionais,<br>\n\u25cf Navegadores (todos eles),<br>\n\u25cf Software de produtividade usados no dia a dia do escrit\u00f3rio,<br>\n\u25cf Aplicativos banc\u00e1rios,<br>\n\u25cf E, \u00e9 claro, a sua <a href=\"https:\/\/www.kaspersky.com.br\/premium?icid=br_bb2022-kdplacehd_acq_ona_smm__onl_b2c_kdaily_lnk_sm-team___kprem___\" target=\"_blank\" rel=\"noopener\">solu\u00e7\u00e3o de seguran\u00e7a<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Priorize a atualiza\u00e7\u00e3o dos aplicativos que mant\u00eam seus dispositivos e dados pessoais protegidos contra ciberataques.<\/p>\n","protected":false},"author":2706,"featured_media":17497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[34,26,331,830,2616,1448,1951,267,230],"class_list":["post-17496","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tips","tag-android","tag-aplicativos","tag-atualizacoes","tag-tips","tag-exploracoes","tag-navegadores","tag-updates","tag-vulnerabilidades","tag-windows"],"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/5-things-that-you-must-update-asap\/17496\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/5-things-that-you-must-update-asap\/22853\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/5-things-that-you-must-update-asap\/18336\/"},{"hreflang":"ar","url":"https:\/\/me.kaspersky.com\/blog\/5-things-that-you-must-update-asap\/9110\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/5-things-that-you-must-update-asap\/24772\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/5-things-that-you-must-update-asap\/22765\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/5-things-that-you-must-update-asap\/25288\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/5-things-that-you-must-update-asap\/24671\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/5-things-that-you-must-update-asap\/30692\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/5-things-that-you-must-update-asap\/9640\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/5-things-that-you-must-update-asap\/39911\/"},{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/5-things-that-you-must-update-asap\/16933\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/5-things-that-you-must-update-asap\/14829\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/5-things-that-you-must-update-asap\/26745\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/5-things-that-you-must-update-asap\/30699\/"},{"hreflang":"nl","url":"https:\/\/www.kaspersky.nl\/blog\/5-things-that-you-must-update-asap\/27053\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/5-things-that-you-must-update-asap\/23890\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/5-things-that-you-must-update-asap\/29230\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/5-things-that-you-must-update-asap\/29027\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/updates\/","name":"updates"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/17496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/2706"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=17496"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/17496\/revisions"}],"predecessor-version":[{"id":17669,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/17496\/revisions\/17669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/17497"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=17496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=17496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=17496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}