{"id":19889,"date":"2022-08-31T17:04:40","date_gmt":"2022-08-31T20:04:40","guid":{"rendered":"https:\/\/www.kaspersky.com.br\/blog\/?p=19889"},"modified":"2022-08-31T17:19:47","modified_gmt":"2022-08-31T20:19:47","slug":"kaspersky-lider-infotech","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/kaspersky-lider-infotech\/19889\/","title":{"rendered":"Kaspersky \u00e9 l\u00edder no Quadrante da Info-Tech"},"content":{"rendered":"<p>A Info-Tech, empresa de pesquisa com atua\u00e7\u00e3o global, lan\u00e7ou recentemente o <a href=\"https:\/\/go.kaspersky.com\/info-tech-quadrant2022\" target=\"_blank\" rel=\"noopener nofollow\">Data Quadrant Report de 2022,<\/a> um estudo que analisou diversas solu\u00e7\u00f5es de prote\u00e7\u00e3o de <em>endpoints<\/em>. E estamos muito orgulhosos em anunciar que o nosso <a href=\"https:\/\/www.kaspersky.com.br\/small-to-medium-business-security\/cloud?reseller=br_b2bevergreen_pro_ona_sem_bra_onl_b2b_goo_ppc-ad_____&amp;utm_content=b2bevergreen&amp;ksid=0269a99c-26cd-46d3-89d6-1160677f119a&amp;ksprof_id=64&amp;ksaffcode=680664&amp;ksdevice=c&amp;kschadid=445457789671&amp;kschname=google&amp;kpid=Google%7C2060964628%7C102676077746%7C445457789671%7Caud-361230807554:kwd-307508372796%7Cc&amp;gclid=CjwKCAjwo_KXBhAaEiwA2RZ8hEDMqhMhU18iUtFbalavoY2b54oGNmnHfzqX-ULuAbHuyCyWh8JbdhoCJBcQAvD_BwE\" target=\"_blank\" rel=\"noopener\">Kaspersky Endpoint Security for Business<\/a> foi reconhecido como l\u00edder no relat\u00f3rio.<\/p>\n<h2>Crit\u00e9rios e ranking<\/h2>\n<p>Fomos o fornecedor com a melhor avalia\u00e7\u00e3o entre os 14 participantes do relat\u00f3rio, com uma pontua\u00e7\u00e3o de 8,9\/10, motivada pelos recursos do produto, satisfa\u00e7\u00e3o dos clientes e experi\u00eancia geral com a organiza\u00e7\u00e3o.<\/p>\n<p><strong>Se voc\u00ea n\u00e3o est\u00e1 familiarizado com o Data Quadrant da Info-Tech<\/strong>, n\u00f3s explicamos: o relat\u00f3rio avalia produtos conhecidos do mercado de prote\u00e7\u00e3o de endpoints para que as empresas possam tomar decis\u00f5es conscientes ao adquirir um software de seguran\u00e7a.\u00a0As tecnologias s\u00e3o classificadas com base nas opini\u00f5es recebidas de clientes reais, como por exemplo profissionais de TI e de neg\u00f3cios. No relat\u00f3rio, todas as solu\u00e7\u00f5es s\u00e3o categorizadas em duas dimens\u00f5es: recursos e satisfa\u00e7\u00e3o do produto, assim como a experi\u00eancia e as capacidades do fornecedor. Isso inclui elementos como implementa\u00e7\u00e3o do programa, treinamento e suporte, al\u00e9m de confiabilidade e respeito do fornecedor.<\/p>\n<p>O <a href=\"https:\/\/www.kaspersky.com.br\/small-to-medium-business-security?icid=br_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\">Kaspersky Endpoint Security for Business<\/a> recebeu a melhor avalia\u00e7\u00e3o nas respostas emocionais (exemplo: quando se questiona se o produto \u00e9 considerado confi\u00e1vel) com 97%. Tamb\u00e9m tivemos a melhor classifica\u00e7\u00e3o dentre todos os fornecedores na an\u00e1lise geral de recursos no produto, com pontua\u00e7\u00e3o de 85%, e estivemos sempre entre os tr\u00eas primeiros fornecedores em dez crit\u00e9rios de an\u00e1lise de recursos avaliados no relat\u00f3rio.<\/p>\n<p>O endpoint ficou em primeiro lugar em quatro das categorias, inclusive integra\u00e7\u00e3o entre plataformas, detec\u00e7\u00e3o din\u00e2mica de malware, funcionalidade NGFW (firewall da pr\u00f3xima gera\u00e7\u00e3o) do host e per\u00edcia (capacidade de fornecer visibilidade total do que aconteceu em um endpoint durante um ataque, em uma exibi\u00e7\u00e3o de f\u00e1cil entendimento). Em quatro dessas categorias, que incluem a integra\u00e7\u00e3o entre plataformas, detec\u00e7\u00e3o din\u00e2mica de malware, funcionalidade de host como NGFW (firewall de pr\u00f3xima gera\u00e7\u00e3o) e an\u00e1lise forense, nosso produto conquistou o primeiro lugar.<\/p>\n<h2>Conhe\u00e7a o KESB<\/h2>\n<p>A prote\u00e7\u00e3o dos <em>endpoints<\/em> \u00e9 uma parte essencial do nosso portf\u00f3lio corporativo. Trata-se de uma medida de seguran\u00e7a fundamental para qualquer organiza\u00e7\u00e3o contra ransomware, malware ou amea\u00e7as web. Juntamente com prote\u00e7\u00e3o de redes e na nuvem, o Kaspersky Endpoint Security for Business fornece as bases da seguran\u00e7a. As empresas ainda podem ampliar sua seguran\u00e7a com solu\u00e7\u00f5es e servi\u00e7os avan\u00e7ados, como monitoramento de performance e prote\u00e7\u00e3o contra APTs (ataque persistente avan\u00e7ado) de acordo com suas necessidades.<\/p>\n<p>\u201c<em>Com o cen\u00e1rio das amea\u00e7as crescendo continuamente, \u00e9 essencial que as empresas garantam sua prote\u00e7\u00e3o completa em todos os endpoints, e temos orgulho de nos posicionar como l\u00edderes nesse campo. Para possibilitar uma prote\u00e7\u00e3o completa para todos os endpoints, nosso produto Kaspersky Endpoint Security for Business incorpora n\u00e3o apenas mecanismos de preven\u00e7\u00e3o de amea\u00e7as de primeira linha, mas tamb\u00e9m funcionalidades avan\u00e7adas de EDR. Os especialistas da Kaspersky trabalham continuamente para aperfei\u00e7oar nossos produtos, tanto em termos dos recursos de seguran\u00e7a, quanto da experi\u00eancia do usu\u00e1rio, e \u00e9 satisfat\u00f3rio ver isso se refletir no mundo real<\/em>\u201c, comenta\u00a0<strong>Roberto Rebou\u00e7as, Gerente-executivo da Kaspersky no Brasil.<\/strong><\/p>\n<p>O relat\u00f3rio completo Data Quadrant da Info-Tech para prote\u00e7\u00e3o de endpoints est\u00e1 dispon\u00edvel\u00a0<a href=\"https:\/\/go.kaspersky.com\/info-tech-quadrant2022\" target=\"_blank\" rel=\"noopener nofollow\">aqui<\/a>.<\/p>\n<p><a href=\"https:\/\/www.kaspersky.com.br\/small-to-medium-business-security?icid=br_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-14628 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2017\/10\/27082036\/kesb-V1-desktop-br-1.png\" alt=\"Amea\u00e7as avan\u00e7adas, identicadas ou n\u00e3o\" width=\"1340\" height=\"400\"><\/a><\/p>\n<p>Para saber mais sobre o Kaspersky Endpoint Security for Business, clique <a href=\"https:\/\/www.kaspersky.com.br\/small-to-medium-business-security?icid=br_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recebemos destaque por nossa prote\u00e7\u00e3o de endpoints, considerada uma solu\u00e7\u00e3o de seguran\u00e7a para todas as necessidades de TI<\/p>\n","protected":false},"author":2706,"featured_media":19902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1119,1655,1656],"tags":[1185,798,1310,3042,1413,124],"class_list":["post-19889","post","type-post","status-publish","format-standard","has-post-thumbnail","category-business","category-enterprise","category-smb","tag-business","tag-empresas","tag-endpoint","tag-info-tech","tag-kaspersky-endpoint-security","tag-kesb"],"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/kaspersky-lider-infotech\/19889\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/kesb\/","name":"KESB"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/19889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/2706"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=19889"}],"version-history":[{"count":8,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/19889\/revisions"}],"predecessor-version":[{"id":19910,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/19889\/revisions\/19910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/19902"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=19889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=19889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=19889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}