{"id":3920,"date":"2014-09-10T19:20:25","date_gmt":"2014-09-10T19:20:25","guid":{"rendered":"http:\/\/kasperskydaily.com\/brazil\/?p=3920"},"modified":"2019-11-22T08:02:44","modified_gmt":"2019-11-22T11:02:44","slug":"apple-pay-seguro-iphone","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/apple-pay-seguro-iphone\/3920\/","title":{"rendered":"Apple Pay: ser\u00e1 que \u00e9 seguro fazer pagamento com seu iPhone?"},"content":{"rendered":"<p>Ontem,\u00a0milhares de internautas e us\u00e1rios assistiram online e ao vivo o lan\u00e7amento dos\u00a0novos dispositivos e do novo sistema de pagamentos da Apple. O evento, que ocorreu\u00a0na Calif\u00f3rnia, mostrou ao mundo o t\u00e3o esperado\u00a0iPhone 6 e, como sempre, dividiu opini\u00f5es entre os usu\u00e1rios e f\u00e3s da companhia: \u201cA Apple n\u00e3o est\u00e1 t\u00e3o boa como costumava ser\u201d; \u201cJ\u00e1 vimos isso no Android\u201d e \u201cToma aqui meu dinheiro. Quero um\u201d. \u00c9 natural que os lan\u00e7amentos da multinacional gerem coment\u00e1rios como estes, no entanto, n\u00f3s da Kaspersky no ocupamos em descobrir como funciona o\u00a0novo sistema de pagamento\u00a0Apple Pay, desenvolvido pela companhia com o envolvimento da Visa, MasterCard e American Express e que tem como base o chip NFC, o sensor de impress\u00f5es digitais Touch ID e o aplicativo Passbook, que armazena passagens, ingressos e cupons de desconto.<\/p>\n<p>Essa nova mec\u00e2nica da Apple mostra que a empresa\u00a0deseja\u00a0fazer com que\u00a0o seu iPhone tenha a mesma utilidade da carteira e cart\u00f5es de cr\u00e9dito dos usu\u00e1rios. Mas ele ser\u00e1 que o sistema \u00e9 seguro o suficiente para voc\u00ea ter certeza de que o seu dinheiro n\u00e3o vai acabar no bolso dos cibercriminosos?<\/p>\n<p>O Apple Pay \u00e9 um sistema de pagamento m\u00f3vel, que combina o princ\u00edpio da presta\u00e7\u00e3o de transa\u00e7\u00f5es com algumas solu\u00e7\u00f5es tecnol\u00f3gicas interessantes: NFC, Touch ID, Passbook. Todas estas solu\u00e7\u00f5es trabalham em conjunto para tornar suas compras online mais confortav\u00e9is e seguras \u2013 pelo menos \u00e9 o que dizem os desenvolvedores da companhia.<\/p>\n<p>Ent\u00e3o, como funciona? Na verdade, praticamente da mesma forma que os cart\u00f5es do PayPass ou PayWave: tudo o que voc\u00ea precisa \u00e9 aproximar o seu smartphone (com a tecnologia NFC) de um sensor na caixa registradora e usar o TouchID para finalizar a compra.<\/p>\n<div class=\"pullquote\">O Apple Pay parece seguro, mas o armazenamento de todas as informa\u00e7\u00f5es de seus cart\u00f5es de cr\u00e9dito em um iPhone pode ser ruim para o bolso.<\/div>\n<p>Para faz\u00ea-lo funcionar, primeiro voc\u00ea precisa digitalizar seus cart\u00f5es de cr\u00e9dito com o seu iPhone para que as informa\u00e7\u00f5es como n\u00famero do cart\u00e3o e data de expira\u00e7\u00e3o v\u00e3o\u00a0direto para o aplicativo Passbook. E depois vem a parte mais interessante e complicada da tecnologia: em vez de usar seus n\u00fameros reais de cart\u00e3o de cr\u00e9dito ou de d\u00e9bito durante o pagamento, um \u00fanico n\u00famero de conta ser\u00e1\u00a0usado. Uma vez criado esse n\u00famero, o mesmo ser\u00e1 atribu\u00eddo a um dispositivo, onde as informa\u00e7\u00f5es do cart\u00e3o s\u00e3o\u00a0armazenadas com criptografia em um chip espec\u00edfico e inserido nos\u00a0novos iPhones e no iWatch. Ou seja,\u00a0voc\u00ea pagar\u00e1 com um c\u00f3digo especial n\u00e3o-identific\u00e1vel\u200b\u200b e n\u00e3o com as suas credenciais verdadeiras.<\/p>\n<p>Tal metodologia \u00e9 boa por duas raz\u00f5es: primeiro, nem uma loja, nem um cibercriminoso (que pode tentar interceptar os dados) podem obter as informa\u00e7\u00f5es dos cart\u00f5es durante uma transa\u00e7\u00e3o. Na pior das hip\u00f3teses, ele ter\u00e1 apenas um n\u00famero simb\u00f3lico. Segundo, mesmo se o n\u00famero for comprometido, n\u00e3o vale de nada, porque s\u00f3 funcionar\u00e1 quando transmitido por meio de um dispositivo espec\u00edfico com o qual foi criado. Se o dispositivo for roubado, entra em cena\u00a0a prote\u00e7\u00e3o Touch ID. Em todo\u00a0caso, h\u00e1 sempre o servi\u00e7o Find My iPhone, que voc\u00ea pode usar para bloquear o seu iPhone ou at\u00e9 mesmo limpar todas as informa\u00e7\u00f5es nele.<\/p>\n<p>Mas ser\u00e1 que este sistema \u00e9 realmente seguro? Dmitry Bestuzhev, especialista da Kaspersky,disse que h\u00e1 um problema: \u201cO Touch ID n\u00e3o funciona corretamente sempre e \u00e9 por isso que a Apple permite acessar o dispositivo com um PIN. Esse esquema de atalho pode ser invadido\u00a0por um cibercriminoso para autorizar pagamentos\u201d.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>Em breve voc\u00ea ser\u00e1 capaz de fazer pagamentos apenas com o seu #iPhone ou #iWatch. Ser\u00e1 que \u00e9 seguro?<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2Fiz4h&amp;text=Em+breve+voc%C3%AA+ser%C3%A1+capaz+de+fazer+pagamentos+apenas+com+o+seu+%23iPhone+ou+%23iWatch.+Ser%C3%A1+que+%C3%A9+seguro%3F\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>H\u00e1 mais uma preocupa\u00e7\u00e3o: a forma como a informa\u00e7\u00e3o ser\u00e1 armazenada nos cart\u00f5es. Como voc\u00ea sabe, quase todos os tipos de dado armazenados no iPhone podem ser sincronizado com dispositivos iOS confi\u00e1veis. E isso n\u00e3o \u00e9 s\u00f3 com rela\u00e7\u00e3o a fotos, mas tamb\u00e9m senhas, armazenadas em um aplicativo chamado Keychain. Ent\u00e3o, se as credenciais dos cart\u00f5es forem armazenados em um mesmo lugar, isso permitir\u00e1 que se o dispositivo estiver sincronizado com outros smartphones, a informa\u00e7\u00e3o seja interceptada.<\/p>\n<p style=\"text-align: right\">Tradu\u00e7\u00e3o: Juliana Costa Santos Dias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ontem,\u00a0milhares de internautas e us\u00e1rios assistiram online e ao vivo o lan\u00e7amento dos\u00a0novos dispositivos e do novo sistema de pagamentos da Apple. O evento, que ocorreu\u00a0na Calif\u00f3rnia, mostrou ao mundo<\/p>\n","protected":false},"author":214,"featured_media":3921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1260,14],"tags":[328,329,325,327,326],"class_list":{"0":"post-3920","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-threats","8":"category-news","9":"tag-apple-pay","10":"tag-iphone-6","11":"tag-nfc","12":"tag-pagamentos-moveis","13":"tag-touch-id"},"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/apple-pay-seguro-iphone\/3920\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/apple-pay\/","name":"Apple Pay"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/3920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3920"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/3920\/revisions"}],"predecessor-version":[{"id":13490,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/3920\/revisions\/13490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/3921"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}