{"id":4934,"date":"2015-03-10T19:56:51","date_gmt":"2015-03-10T19:56:51","guid":{"rendered":"http:\/\/kasperskydaily.com\/brazil\/?p=4934"},"modified":"2019-11-22T07:59:46","modified_gmt":"2019-11-22T10:59:46","slug":"diario-do-homem-bionico-002-o-momento-em-que-o-chip-comecou-a-se-mover-dentro-do-meu-corpo","status":"publish","type":"post","link":"https:\/\/www.kaspersky.com.br\/blog\/diario-do-homem-bionico-002-o-momento-em-que-o-chip-comecou-a-se-mover-dentro-do-meu-corpo\/4934\/","title":{"rendered":"Di\u00e1rio do Homem Bi\u00f4nico 002: o momento em que o chip come\u00e7ou a se mover dentro do meu corpo"},"content":{"rendered":"<p>Durante as minhas primeiras duas semanas da experi\u00eancia com o biochip eu tive\u00a0tempo para pensar\u00a0sobre muitas\u00a0coisas. A enxurrada de perguntas da comunidade cibern\u00e9tica me ajudou ainda mais neste processo: uma coisa \u00e9 quando voc\u00ea est\u00e1 sozinho com os seus pensamentos e preocupa\u00e7\u00f5es, mas quando voc\u00ea est\u00e1 constantemente sendo bombardeado com perguntas e sugest\u00f5es, e vive no meio de um ambiente de discuss\u00e3o sobre todos os aspectos do experimento, \u00e9 uma hist\u00f3ria totalmente diferente. Algumas perguntas abordavam quest\u00f5es s\u00e9rias, tais como conforto emocional e religi\u00e3o.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">A hist\u00f3ria do homem que implantou um <a href=\"https:\/\/twitter.com\/hashtag\/chip?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#chip<\/a> no corpo: <a href=\"http:\/\/t.co\/a5LEsPq5c0\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/a5LEsPq5c0<\/a> <a href=\"http:\/\/t.co\/bG8tppnRQ3\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/bG8tppnRQ3<\/a><\/p>\n<p>\u2014 Kaspersky Brasil (@Kasperskybrasil) <a href=\"https:\/\/twitter.com\/Kasperskybrasil\/status\/575325091761885184?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">March 10, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Eu nunca me arrependi do que eu fa\u00e7o. Muito pelo contr\u00e1rio, a quantidade de perguntas, assim como os seus assuntos variados, provaram que toda a iniciativa n\u00e3o foi em v\u00e3o. De fato esta tecnologia \u00e9 realmente pol\u00eamica. A fim de evitar de que o cen\u00e1rio do filme \u201cBlade Runner\u201d aconte\u00e7a na vida real, precisamos melhorar, atualizar, redefinir e depurar seriamente\u00a0essa tecnologia.<\/p>\n<p>Em primeiro lugar, eu preciso falar sobre todos os aspectos. A sensa\u00e7ao do chip sob a pele \u00e9 a primeira coisa pela qual se deve acostumar.<\/p>\n<p>Com rela\u00e7\u00e3o a isso eu praticamente n\u00e3o o sinto. Talvez este ponto do corpo entre o polegar e o dedo indicador tenham um n\u00famero muito pequeno de terminais nervosos, ou, caso contr\u00e1rio, a cirurgia foi um enorme sucesso. A quest\u00e3o \u00e9 que o chip parece ter encontrado um lugar c\u00f4modo para habitar.<\/p>\n<p>No\u00a0entanto, t\u00eam vezes que eu o sinto dentro da minha m\u00e3o. Quando eu levanto coisas pesadas como as sacolas do mercado, sinto como o chip se movesse uns mil\u00edmetros em dire\u00e7\u00e3o ao dedo indicador.<\/p>\n<p>Em outros momento, eu acordo e vejo que\u00a0o chip viajou para outro lugar durante a\u00a0noite. N\u00e3o h\u00e1 nada de errado com isso, j\u00e1 que\u00a0a dist\u00e2ncia m\u00e1xima que ele pode recorrer \u00e9 equivalente ao di\u00e2metro de uma moeda.<\/p>\n<p>Depois de ter vivido desta maneira durante um par de semanas, devo declarar o seguinte: embora\u00a0a id\u00e9ia de colocar um chip em mim tenha sido, em muitos aspectos, maravilhosa (eu gostaria de ressaltar\u00a0todas as suas vantagens iniciais no meu pr\u00f3ximo post no blog), a primeira coisa que deve mudar \u2013 radicalmente! \u2013 \u00e9 a\u00a0forma do chip.<\/p>\n<p>Os biochips de hoje, em geral, s\u00e3o parecidos com este:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4935\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2015\/03\/06141339\/1_ig_EN.png\" alt=\"1_ig_EN\" width=\"800\" height=\"800\"><\/p>\n<p>O recipiente \u00e9 feito de um vidro bio-compat\u00edvel USP absolutamente liso e duro que n\u00e3o \u00e9 descartado pelo corpo e que armazena um pequeno circuito com uma s\u00e9rie de fun\u00e7\u00f5es l\u00f3gicas: um bloco de leitura\/grava\u00e7\u00e3o e um bloco de mem\u00f3ria que \u00e9 ativado no campo do receptor RFID.<\/p>\n<p>Isso significa que o chip \u00e9 ativado somente quando posicionado na proximidade de um determinado objeto, tal como um leitor de pagamento para cart\u00f5es de cr\u00e9dito.<\/p>\n<p>Em geral, funciona bem. No entanto, uma vez que o dispositivo est\u00e1 pensado para permanecer por um tempo prolongado sob a pele, sua forma n\u00e3o \u00e9 a ideal.<\/p>\n<p><strong>Onde localizar o chip, segundo Da Vinci\u00a0<\/strong><\/p>\n<p>Em primeiro lugar, o local entre o polegar e o dedo indicador n\u00e3o foi a melhor regi\u00e3o para colocar o chip, uma vez que no uso di\u00e1rio n\u00e3o \u00e9 conveniente. Por\u00a0exemplo, quando eu passo pelo port\u00e3o de pagamento do metr\u00f4, intuitivamente eu fa\u00e7o um gesto de deslizar ou tocar o leitor com o punho ou o pulso.<\/p>\n<div class=\"pullquote\">Fa\u00e7a as coisas o mais simples poss\u00edvel, mas n\u00e3o mais simples<\/div>\n<p>Durante este \u00faltimo tempo eu me aproximei de diferentes leitores, e posso garantir que o chip deveria empregar os mesmos testes de usabilidade e testes de experi\u00eancia do usu\u00e1rio que\u00a0os aplicativos m\u00f3veis. \u00c9 a l\u00f3gica da l\u00e2mina do Okkama. Com rela\u00e7\u00e3o a isso, eu gosto do que Albert Einstein dizia claramente:<\/p>\n<p>\u201cFa\u00e7a as coisas o mais simples poss\u00edvel, mas n\u00e3o mais simples.\u201d<\/p>\n<p>Quando aplicado ao chip na minha m\u00e3o, ele deve ser colocado de tal maneira que permita uma intera\u00e7\u00e3o confort\u00e1vel com qualquer dispositivo ao alcance da m\u00e3o. Da Vinci j\u00e1 deu a entender sobre esta abordagem no\u00a0Homem Vitruviano.<\/p>\n<p>Enquanto eu andava de metr\u00f4, passando por pr\u00e9dios de escrit\u00f3rios e shopping centers (o chip ainda n\u00e3o serve como meio de admiss\u00e3o, mesmo que os leitores tenham reagido em sua presen\u00e7a), eu ia identificando os pontos que poderiam ser adequados para a implanta\u00e7\u00e3o do chip:<\/p>\n<p>A zona mais conveniente para implantar este dispositivo seria o\u00a0centro do lado externo da m\u00e3o. Se o chip \u00e9 implantado neste ponto, o portador poderia desbloquear muitos tipos de fechaduras, pagar em terminais de pontos de venda, interagir com smartphones e tablets, e pagar o transporte p\u00fablico com um movimento natural.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4937\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2015\/03\/06141333\/4_ig_EN.png\" alt=\"4_ig_EN\" width=\"800\" height=\"800\"><\/p>\n<p>#2 na minha lista pessoal de melhores lugares est\u00e1 a zona localizada no dorso\u00a0da m\u00e3o, isto \u00e9 entre o dedo mindinho e o pulso: se voc\u00ea fechar o punho, voc\u00ea ver\u00e1 que ali se forma uma pequena ruga precisamente onde o chip poderia ser implantado.<\/p>\n<p>#3 o terceiro lugar est\u00e1 localizado entre os n\u00f3s dos dedos. Neste caso, com o intuito de interagir com um leitor, voc\u00ea pode acion\u00e1-lo com o punho, que \u00e9 um movimento muito intuitivo.<\/p>\n<p>Na verdade, n\u00e3o existe uma solu\u00e7\u00e3o ideal aqui. Para que uma zona de implanta\u00e7\u00e3o de chip seja\u00a0universal, devemos unificar todos os leitores do planeta.<\/p>\n<p>Mas, inclusive se decidimos fazer o \u00faltimo, tamb\u00e9m n\u00e3o seria nada f\u00e1cil. As pessoas s\u00e3o muito diferentes: elas variam na altura, se \u00e9 destro ou canhoto, pode ter problemas com extremidades\u00a0ou at\u00e9 mesmo n\u00e3o ter extremidades\u00a0em tudo.<\/p>\n<p>Para atender aos interesses de toda a humanidade, poder\u00edamos implantar v\u00e1rios chips em um mesmo indiv\u00edduo. Assim poder\u00edamos interagir e realizar diversas tarefas, tais como faz uma rede local.<\/p>\n<p>Tecnicamente, esta segunda op\u00e7\u00e3o \u00e9 plaus\u00edvel, mas est\u00e1 vinculada a v\u00e1rios riscos de seguran\u00e7a extras: potenciais atacantes poderiam acessar remotamente os dados compartilhados entre os chips usando uma antena de feixe \u2013 um m\u00e9todo amplamente utilizado para realizar ataques\u00a0via Bluetooth.<\/p>\n<h3>O biochip tem que criar ra\u00edzes<\/h3>\n<p>A\u00a0localiza\u00e7\u00e3o do chip \u00e9 apenas uma pequena parte de um problema maior. Lembra que eu disse que o chip viaja sob a pele? Este problema tamb\u00e9m tem que ser resolvido. Eu empreguei todas as minhas habilidades de gest\u00e3o de produtos e veio\u00a0a solu\u00e7\u00e3o do seguinte modo:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4944\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2015\/03\/06141327\/2_EN.jpg\" alt=\"2_EN\" width=\"1869\" height=\"1333\"><\/p>\n<p>\u00a0<\/p>\n<p>Para que um biochip se torne em um dispositivo f\u00e1cil de usar, tem que ser reformulado e adaptado para atender \u00e0s necessidades dos usu\u00e1rios. O principal requisito neste sentido depende da condi\u00e7\u00e3o do pr\u00f3prio chip:<\/p>\n<p>1) Antes e durante o processo de implanta\u00e7\u00e3o;<br>\n2) Ap\u00f3s a implanta\u00e7\u00e3o;<br>\n3) Antes da extra\u00e7\u00e3o (em casos de que o portador, por alguma raz\u00e3o, decida se livrar dele).<\/p>\n<p>Na sua primeira condi\u00e7\u00e3o, o chip deve ser liso e compacto com o fim de passar sob sua pele da melhor maneira poss\u00edvel e ser absolutamente impalp\u00e1vel. O chip tamb\u00e9m deve permanecer no modo de espera e desativado.<\/p>\n<p>Ap\u00f3s a implanta\u00e7\u00e3o, o usu\u00e1rio deve ser capaz de fazer duas coisas essenciais. A primeira delas \u00e9 poder invocar o chip, literalmente: a \u00fanica vez que o chip se sente perfeitamente e n\u00e3o se move sob a pele \u00e9 quando cria ra\u00edzes no corpo do usu\u00e1rio.<\/p>\n<p>Para que isso aconte\u00e7a, o chip precisa criar \u201cra\u00edzes\u201d muito finas para fixar-se de forma est\u00e1vel no organismo vivo e torne-se parte integrante. Ao mesmo tempo, essas \u201cra\u00edzes\u201d funcionam como meio para que o chip ligue ou se conecte ao sistema neuronal.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4945\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/94\/2015\/12\/06135443\/3_EN.png\" alt=\"3_EN\" width=\"1869\" height=\"1333\"><\/p>\n<p>No entanto, poderia chegar o momento em que o usu\u00e1rio queira se desfazer do chip, qualquer que seja o motivo, atualiz\u00e1-lo, substitu\u00ed-lo por um mais sofisticado ou porque padece de tecnofobia.<\/p>\n<p>Nesse caso, eu deveria ter a oportunidade de acessar imediatamente os meus dados pessoais, criptograf\u00e1-los e envi\u00e1-los para a nuvem, para que o chip seja destru\u00eddo definitivamente. Para isso, ser\u00e1 necess\u00e1rio um bisturi, um anest\u00e9sico e um par de pin\u00e7as.\u00a0H\u00e1 mais uma op\u00e7\u00e3o: esses chips se dissolvem assim que sejam\u00a0desativados.<\/p>\n<h3>O segundo requisito: simbiose<\/h3>\n<p>Houve uma pergunta muito popular entre os leitores: \u201cOs cibercriminosos poderia cortar a m\u00e3o dos usu\u00e1rios para poder usar o chip?\u201d Infelizmente, eu tenho que admitir que \u00e9 bastante vi\u00e1vel.<\/p>\n<p>H\u00e1 milh\u00f5es de coisas que os criminosos teriam que conhecer para este corte brutal. Em primeiro lugar, saber exatamente onde se encontra o chip e, em \u00faltima inst\u00e2ncia, cortar um peda\u00e7o de carne \u00e9 muito mais complexo que roubar senhas atrav\u00e9s da Internet, ent\u00e3o o criminosos teria que estar em uma situa\u00e7\u00e3o extremamente desesperadora. Mas, em geral, \u00e9 um ponto muito justo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Me talking to office security ppl explaining how the biochip in my hand would be used as office key <a href=\"https:\/\/twitter.com\/hashtag\/BionicManDiary?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#BionicManDiary<\/a> <a href=\"http:\/\/t.co\/l99jgYdwld\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/l99jgYdwld<\/a><\/p>\n<p>\u2014 Evgeny Chereshnev (@cheresh) <a href=\"https:\/\/twitter.com\/cheresh\/status\/570613671308754945?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">February 25, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Para evitar\u00a0esta vulnerabilidade, o chip teria que estar completamente inoperante quando separado do portador leg\u00edtimo. Se o chip for extra\u00eddo desta forma do corpo, teria que danific\u00e1-lo sem possibilidade de repara\u00e7\u00e3o.<\/p>\n<p>Devem existir m\u00e9todos para evitar o roubo de dados em qualquer dos cen\u00e1rios possiv\u00e9is. Para reduzir as probabilidade de que o chip seja hackeado, poderiam ser empregados outros fatores de autentica\u00e7\u00e3o, tais como o reconhecimento de voz ou um token de hardware situado em um lugar conhecido unicamente pelo propriet\u00e1rio leg\u00edtimo.<\/p>\n<p>Sinta-se livre para sugerir nos coment\u00e1rios os cen\u00e1rios que voc\u00ea imagine: como voc\u00ea v\u00ea o uso do chip? Quais casos de uso devem ser levados em considera\u00e7\u00e3o? \u00c9 disso que se trata todo o experimento: testar as ideias mais loucas que poderiam abrir o caminho para importantes descobertas.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>#BionicManDiary 002 \u2013 o momento em que\u00a0chip come\u00e7ou se mover no meu corpo<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2FnZP2&amp;text=%23BionicManDiary+002+%26%238211%3B+o+momento+em+que%C2%A0chip+come%C3%A7ou+se+mover+no+meu+corpo\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>O meu pr\u00f3ximo texto do di\u00e1rio estar\u00e1 focado em duas quest\u00f5es: como eu consegui ignorar a senha do meu pr\u00f3prio biochip para desbloquear o\u00a0celular, e os resultados que quero transmitir para os desenvolvedores de aplicativos.<\/p>\n<p>Meus\u00a0melhores cumprimentos,<br>\nCHE<\/p>\n<p>OBS:\u00a0\u00a0Todos os posts do blog e tweets sobre este assunto podem ser encontrados na hashtag \u00a0#BionicManDiary.<br>\nVoc\u00ea pode perguntar o que voc\u00ea deseje\u00a0(sem limita\u00e7\u00f5es!) via Facebook ou Twitter. Eu farei o meu melhor para responder todas as perguntas.<\/p>\n<p style=\"text-align: right\"><em>Tradu\u00e7\u00e3o: Juliana Costa Santos Dias<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante as minhas primeiras duas semanas da experi\u00eancia com o biochip eu tive\u00a0tempo para pensar\u00a0sobre muitas\u00a0coisas. A enxurrada de perguntas da comunidade cibern\u00e9tica me ajudou ainda mais neste processo: uma<\/p>\n","protected":false},"author":7,"featured_media":4938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1260,14],"tags":[540,566,564,567,462,412,325,53,565,40],"class_list":["post-4934","post","type-post","status-publish","format-standard","has-post-thumbnail","category-threats","category-news","tag-biochip","tag-biohacking","tag-bionicmandiary","tag-conceito","tag-dados-privados","tag-futuro","tag-nfc","tag-privacidade","tag-rfid","tag-seguranca"],"hreflang":[{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/diario-do-homem-bionico-002-o-momento-em-que-o-chip-comecou-a-se-mover-dentro-do-meu-corpo\/4934\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.com.br\/blog\/tag\/biochip\/","name":"biochip"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/4934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4934"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/4934\/revisions"}],"predecessor-version":[{"id":13399,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/posts\/4934\/revisions\/13399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media\/4938"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}